{"id":14241,"date":"2019-06-18T09:30:59","date_gmt":"2019-06-18T12:30:59","guid":{"rendered":"http:\/\/www.cardenalspinola.com.ar\/v2\/?page_id=14241"},"modified":"2022-05-29T21:51:35","modified_gmt":"2022-05-30T00:51:35","slug":"admisiones-nivel-secundario","status":"publish","type":"page","link":"https:\/\/www.cardenalspinola.com.ar\/v3\/el-colegio\/admisiones\/admisiones-nivel-secundario\/","title":{"rendered":"Admisiones Nivel Secundario"},"content":{"rendered":"<p class=\"p1\">Para solicitar admisi\u00f3n en el Nivel Secundario del Colegio a partir del ciclo 2023, complete el siguiente formulario.<br \/>\nTenga en cuenta que la recepci\u00f3n del mismo no implica reserva de vacante. <span style=\"color: #ff0000;\"><em><strong>*Informaci\u00f3n obligatoria.<\/strong><\/em><\/span><\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f15939-o1\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/v3\/wp-json\/wp\/v2\/pages\/14241#wpcf7-f15939-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"15939\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.7\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f15939-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:15939,&quot;conditions&quot;:[{&quot;then_field&quot;:&quot;hermano&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;hermanoOK&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;SI&quot;}]}],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;notice_dismissed_rollback-cf7-5.6.3&quot;:true,&quot;notice_dismissed_rollback-cf7-5.6.4&quot;:true}}\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> A\u00f1o solicitado:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sala\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"sala\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"1er. a\u00f1o\">1er. a\u00f1o<\/option><option value=\"2do. a\u00f1o\">2do. a\u00f1o<\/option><option value=\"3er. a\u00f1o\">3er. a\u00f1o<\/option><option value=\"4to. a\u00f1o\">4to. a\u00f1o<\/option><option value=\"5to. a\u00f1o\">5to. a\u00f1o<\/option><option value=\"6to. a\u00f1o\">6to. a\u00f1o<\/option><\/select><\/span><\/label><br \/>\n<span style=\"color: #ff0000;\"><strong>*<\/strong><\/span> Tipo de Jornada<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"jornada\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><input type=\"radio\" name=\"jornada\" value=\"Jornada Simple\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">Jornada Simple<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"radio\" name=\"jornada\" value=\"Jornada Simple con School of English\" \/><span class=\"wpcf7-list-item-label\">Jornada Simple con School of English<\/span><\/span><\/span><\/span><br \/>\n<hr \/>\n<\/p>\n<h2>Datos del Alumno\n<\/h2>\n<p><label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Nombre y Apellido<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> DNI<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"dni\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"dni\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Nacionalidad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nacionalidad\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nacionalidad\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span>Fecha de nacimiento<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nac-dd\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" id=\"nac-dd\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"DD\" value=\"\" type=\"date\" name=\"nac-dd\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Lugar de Nacimiento<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"lugar-nac\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"lugar-nac\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Colegio actual<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"col-actual\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"col-actual\" \/><\/span> <\/label><br \/>\n<label>Otros colegios a los que asisti\u00f3 (si corresponde)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"col-otros\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"col-otros\" \/><\/span> <\/label>\n<\/p>\n<p>\u00bfEs hermano de un alumno actual del colegio?: <span class=\"wpcf7-form-control-wrap\" data-name=\"hermanoOK\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><input type=\"radio\" name=\"hermanoOK\" value=\"NO\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">NO<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"radio\" name=\"hermanoOK\" value=\"SI\" \/><span class=\"wpcf7-list-item-label\">SI<\/span><\/span><\/span><\/span>\n<\/p>\n<div data-id=\"hermano\" data-orig_data_id=\"hermano\" data-clear_on_hide data-class=\"wpcf7cf_group\">\n\t<h2>Datos del Hermano\/a\n\t<\/h2>\n\t<p><label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Nombre y Apellido<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"bro-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"bro-name\" \/><\/span> <\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Grado o sala (requerido): <span class=\"wpcf7-form-control-wrap\" data-name=\"bro-grado\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"bro-grado\" \/><\/span> <\/label>&nbsp;<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Nivel (requerido): <span class=\"wpcf7-form-control-wrap\" data-name=\"bro-nivel\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"bro-nivel\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"Nivel Inicial\">Nivel Inicial<\/option><option value=\"Nivel Primario\">Nivel Primario<\/option><option value=\"Nivel Secundario\">Nivel Secundario<\/option><\/select><\/span><\/label>\n\t<\/p>\n<\/div>\n<hr \/>\n<h2>Datos del Adulto Responsable\n<\/h2>\n<p><label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span>V\u00ednculo con el alumno<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"vinculo\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"vinculo\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"Madre\">Madre<\/option><option value=\"Padre\">Padre<\/option><option value=\"Tutor \/ Encargado\">Tutor \/ Encargado<\/option><\/select><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Nombre y Apellido<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nombreResponsable\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nombreResponsable\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span>Nacionalidad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"NacionalidadResponsable\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"NacionalidadResponsable\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Ocupaci\u00f3n<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"OcupacionResponsable\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"OcupacionResponsable\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span>Direcci\u00f3n<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"DireccionResponsable\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"DireccionResponsable\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span> Localidad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"BarrioResponsable\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"BarrioResponsable\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* <\/strong><\/span>Tel\u00e9fono principal<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-resp\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-resp\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Tel\u00e9fono secundario<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-resp2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-resp2\" \/><\/span><br \/>\n<\/label><br \/>\n<label><span style=\"color: #ff0000;\"><strong>* Correo Electr\u00f3nico<\/strong><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label><i style=\"font-size:10pt;font-style:italic;\">Nos contactaremos con usted a \u00e9sta direcci\u00f3n de correo.<\/i><br \/>\n<label> \u00bfEs ex-alumno?<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ex-alumno\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><input type=\"radio\" name=\"ex-alumno\" value=\"SI\" \/><span class=\"wpcf7-list-item-label\">SI<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"radio\" name=\"ex-alumno\" value=\"NO\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">NO<\/span><\/span><\/span><\/span><br \/>\n<hr \/>\n<\/p>\n<h2>Datos del Adulto Responsable Adicional\n<\/h2>\n<p><label> V\u00ednculo con el ni\u00f1o<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"vinculo2\"><select class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\" name=\"vinculo2\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"Madre\">Madre<\/option><option value=\"Padre\">Padre<\/option><option value=\"Tutor \/ Encargado\">Tutor \/ Encargado<\/option><\/select><\/span><br \/>\n<\/label><br \/>\n<label> Nombre y Apellido<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"nombreResponsable2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nombreResponsable2\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Nacionalidad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"NacionalidadResponsable2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"NacionalidadResponsable2\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Ocupaci\u00f3n<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"OcupacionResponsable2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"OcupacionResponsable2\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Direcci\u00f3n<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"DireccionResponsable2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"DireccionResponsable2\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Localidad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"BarrioResponsable2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"BarrioResponsable2\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Tel\u00e9fono principal<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-resp3\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-resp3\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Tel\u00e9fono secundario<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-resp4\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-resp4\" \/><\/span><br \/>\n<\/label><br \/>\n<label> Correo electr\u00f3nico<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email2\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-email\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email2\" \/><\/span> <\/label><br \/>\n<label> \u00bfEs ex-alumno?<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"ex-alumno2\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><input type=\"radio\" name=\"ex-alumno2\" value=\"SI\" \/><span class=\"wpcf7-list-item-label\">SI<\/span><\/span><span class=\"wpcf7-list-item last\"><input type=\"radio\" name=\"ex-alumno2\" value=\"NO\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">NO<\/span><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control has-spinner wpcf7-submit\" type=\"submit\" value=\"Enviar solicitud\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Para solicitar admisi\u00f3n en el Nivel Secundario del Colegio a partir del ciclo 2023, complete el siguiente formulario. Tenga en cuenta que la recepci\u00f3n del mismo no implica reserva de vacante. *Informaci\u00f3n obligatoria.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3867,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/pages\/14241"}],"collection":[{"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/comments?post=14241"}],"version-history":[{"count":5,"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/pages\/14241\/revisions"}],"predecessor-version":[{"id":17497,"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/pages\/14241\/revisions\/17497"}],"up":[{"embeddable":true,"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/pages\/3867"}],"wp:attachment":[{"href":"https:\/\/www.cardenalspinola.com.ar\/v3\/wp-json\/wp\/v2\/media?parent=14241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}